{"id":27689,"date":"2021-12-01T20:43:39","date_gmt":"2021-12-01T20:43:39","guid":{"rendered":"https:\/\/enchereschampagne.com\/en\/?p=27689"},"modified":"2021-12-01T20:44:53","modified_gmt":"2021-12-01T20:44:53","slug":"prestige-sale-8","status":"publish","type":"post","link":"https:\/\/enchereschampagne.com\/en\/prestige-sale-8\/","title":{"rendered":"Canadian and International Fine Art Auction"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]\n<h3><strong>December 14th 2021, 7:00 PM<\/strong><\/h3>\n[\/vc_column_text][vc_column_text el_class=&#8221;short_hidden&#8221;]Featuring an exceptional selection of\u00a0<strong>paintings, drawings, lithographs and sculptures<\/strong>\u00a0from the best\u00a0<strong>artists<\/strong>\u00a0carefully assembled in our catalog.[\/vc_column_text][vc_column_text]<strong>Viewing<br \/>\n<\/strong>Thursday december 9th 10:00 AM to 5:00 PM<br \/>\nFriday december 10th 10:00 AM to 5:00 PM<br \/>\nSaturday december 11th 10:00 AM to 4:00 PM<br \/>\nSunday december 12th 10:00 AM to 4:00 PM<br \/>\nMonday december 13th 10:00 AM to 5:00 PM<br \/>\nTuesday december 14th\u00a010:00 AM to 4:00 PM<\/p>\n<div><\/div>\n<p><strong>Online auction<\/strong><\/p>\n<a href=\"https:\/\/live.enchereschampagne.com\/auctions\/4-4GA7OE\/art-international-et-canadien-international-and-canadian-art?limit=96\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#daa66e;border-color:#af8558;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#e6c19a;border-radius:5px;text-shadow:none\"> CATALOGUE<\/span><\/a>[\/vc_column_text][vc_column_text el_class=&#8221;short_hidden&#8221;]<em>For more details on items for sale, contact us by phone at (438) 387-3100<\/em>[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>December 14th 2021, 7:00 PM<\/p>\n","protected":false},"author":1,"featured_media":27690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-27689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet-auction"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canadian and International Fine Art Auction<\/title>\n<meta name=\"description\" content=\"14 d\u00e9cembre 2021, 19H00December 14th 2021, 7:00 PM\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enchereschampagne.com\/en\/prestige-sale-8\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canadian and International Fine Art Auction\" \/>\n<meta property=\"og:description\" content=\"14 d\u00e9cembre 2021, 19H00December 14th 2021, 7:00 PM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enchereschampagne.com\/en\/prestige-sale-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Ench\u00e8res Champagne Auctions\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/champagneauctions\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T20:43:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T20:44:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"984\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/person\\\/5ee9d9f4c42b7890e9208a4e08eae9e7\"},\"headline\":\"Canadian and International Fine Art Auction\",\"datePublished\":\"2021-12-01T20:43:39+00:00\",\"dateModified\":\"2021-12-01T20:44:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/\"},\"wordCount\":282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021.jpg\",\"articleSection\":[\"Internet Auction\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/#respond\"]}]},{\"@type\":\"event\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/\",\"name\":\"Canadian and International Fine Art Auction\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/#primaryimage\"},\"image\":[\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021-1170x600.jpg\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021-300x154.jpg\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021-1024x525.jpg\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021.jpg\"],\"thumbnailUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021.jpg\",\"datePublished\":\"2021-12-01T20:43:39+00:00\",\"dateModified\":\"2021-12-01T20:44:53+00:00\",\"description\":\"December 14th 2021, 7:00 PM\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/\"]}],\"@context\":\"https:\\\/\\\/schema.org\",\"startDate\":\"2021-12-14T07:00:00+00:00\",\"endDate\":\"2021-12-14T11:55:00+00:00\",\"eventStatus\":\"EventMovedOnline\",\"eventAttendanceMode\":\"OnlineEventAttendanceMode\",\"location\":{\"@type\":\"VirtualLocation\",\"url\":\"https:\\\/\\\/live.enchereschampagne.com\\\/\"},\"offers\":{\"@type\":\"Offer\"}},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021.jpg\",\"contentUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Fine-Art-Cover-Dec-2021.jpg\",\"width\":1920,\"height\":984},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/prestige-sale-8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enchereschampagne.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art Canadien et International\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#website\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/\",\"name\":\"Ench\u00e8res Champagne Auctions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enchereschampagne.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\",\"name\":\"Ench\u00e8res Champagne Auctions\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo_enchereChampagne.png\",\"contentUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo_enchereChampagne.png\",\"width\":192,\"height\":65,\"caption\":\"Ench\u00e8res Champagne Auctions\"},\"image\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/champagneauctions\",\"https:\\\/\\\/www.instagram.com\\\/champagneauctions\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/person\\\/5ee9d9f4c42b7890e9208a4e08eae9e7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canadian and International Fine Art Auction","description":"14 d\u00e9cembre 2021, 19H00December 14th 2021, 7:00 PM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enchereschampagne.com\/en\/prestige-sale-8\/","og_locale":"en_US","og_type":"article","og_title":"[:fr]Art Canadien et International[:en]Canadian and International Fine Art Auction[:] - Ench\u00e8res Champagne Auctions","og_description":"14 d\u00e9cembre 2021, 19H00December 14th 2021, 7:00 PM","og_url":"https:\/\/enchereschampagne.com\/en\/prestige-sale-8\/","og_site_name":"Ench\u00e8res Champagne Auctions","article_publisher":"http:\/\/www.facebook.com\/champagneauctions","article_published_time":"2021-12-01T20:43:39+00:00","article_modified_time":"2021-12-01T20:44:53+00:00","og_image":[{"width":1920,"height":984,"url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/#article","isPartOf":{"@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/"},"author":{"name":"admin","@id":"https:\/\/enchereschampagne.com\/#\/schema\/person\/5ee9d9f4c42b7890e9208a4e08eae9e7"},"headline":"Canadian and International Fine Art Auction","datePublished":"2021-12-01T20:43:39+00:00","dateModified":"2021-12-01T20:44:53+00:00","mainEntityOfPage":{"@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/"},"wordCount":282,"commentCount":0,"publisher":{"@id":"https:\/\/enchereschampagne.com\/#organization"},"image":{"@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/#primaryimage"},"thumbnailUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021.jpg","articleSection":["Internet Auction"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/enchereschampagne.com\/prestige-sale-8\/#respond"]}]},{"@type":"event","@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/","url":"https:\/\/enchereschampagne.com\/prestige-sale-8\/","name":"Canadian and International Fine Art Auction","isPartOf":{"@id":"https:\/\/enchereschampagne.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/#primaryimage"},"image":["https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021-1170x600.jpg","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021-300x154.jpg","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021-1024x525.jpg","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021.jpg"],"thumbnailUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021.jpg","datePublished":"2021-12-01T20:43:39+00:00","dateModified":"2021-12-01T20:44:53+00:00","description":"December 14th 2021, 7:00 PM","breadcrumb":{"@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enchereschampagne.com\/prestige-sale-8\/"]}],"@context":"https:\/\/schema.org","startDate":"2021-12-14T07:00:00+00:00","endDate":"2021-12-14T11:55:00+00:00","eventStatus":"EventMovedOnline","eventAttendanceMode":"OnlineEventAttendanceMode","location":{"@type":"VirtualLocation","url":"https:\/\/live.enchereschampagne.com\/"},"offers":{"@type":"Offer"}},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/#primaryimage","url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021.jpg","contentUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2021\/12\/Fine-Art-Cover-Dec-2021.jpg","width":1920,"height":984},{"@type":"BreadcrumbList","@id":"https:\/\/enchereschampagne.com\/prestige-sale-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enchereschampagne.com\/"},{"@type":"ListItem","position":2,"name":"Art Canadien et International"}]},{"@type":"WebSite","@id":"https:\/\/enchereschampagne.com\/#website","url":"https:\/\/enchereschampagne.com\/","name":"Ench\u00e8res Champagne Auctions","description":"","publisher":{"@id":"https:\/\/enchereschampagne.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enchereschampagne.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/enchereschampagne.com\/#organization","name":"Ench\u00e8res Champagne Auctions","url":"https:\/\/enchereschampagne.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enchereschampagne.com\/#\/schema\/logo\/image\/","url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2019\/01\/logo_enchereChampagne.png","contentUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2019\/01\/logo_enchereChampagne.png","width":192,"height":65,"caption":"Ench\u00e8res Champagne Auctions"},"image":{"@id":"https:\/\/enchereschampagne.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/champagneauctions","https:\/\/www.instagram.com\/champagneauctions"]},{"@type":"Person","@id":"https:\/\/enchereschampagne.com\/#\/schema\/person\/5ee9d9f4c42b7890e9208a4e08eae9e7","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/27689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/comments?post=27689"}],"version-history":[{"count":2,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/27689\/revisions"}],"predecessor-version":[{"id":27692,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/27689\/revisions\/27692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/media\/27690"}],"wp:attachment":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/media?parent=27689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/categories?post=27689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/tags?post=27689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}