{"id":28101,"date":"2023-02-03T21:07:13","date_gmt":"2023-02-03T21:07:13","guid":{"rendered":"https:\/\/enchereschampagne.com\/?p=28101"},"modified":"2023-02-03T21:15:21","modified_gmt":"2023-02-03T21:15:21","slug":"vente-decouverte","status":"publish","type":"post","link":"https:\/\/enchereschampagne.com\/en\/vente-decouverte\/","title":{"rendered":"DISCOVERY SALE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]\r\n<h3><strong>February 21st &#038; 22nd 2023, 6:00 PM<\/strong><\/h3>\r\n[\/vc_column_text][vc_column_text el_class=&#8221;short_hidden&#8221;]Prepared for the discerning collector, this sale is dedicated to <strong>fine art, silverware, antiques and more<\/strong>\u00a0carefully assembled in our catalog.[\/vc_column_text][vc_column_text]<strong>Online auction\r\n<\/strong>\r\n\r\n<a href=\"https:\/\/live.enchereschampagne.com\/auctions\/4-8RI9Z8\/vente-dcouverte-discovery-sale-12\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#daa66e;border-color:#af8558;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#e6c19a;border-radius:5px;text-shadow:none\"> SESSION 1<\/span><\/a> <a href=\"https:\/\/live.enchereschampagne.com\/auctions\/4-8RIA9S\/vente-dcouverte-discovery-sale-22\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#daa66e;border-color:#af8558;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#e6c19a;border-radius:5px;text-shadow:none\"> SESSION 2<\/span><\/a>[\/vc_column_text][vc_column_text el_class=&#8221;short_hidden&#8221;]\r\n\r\n<em>For more details on items for sale, contact us by phone at (438) 387-3100<\/em>\r\n\r\n[\/vc_column_text][\/vc_column][\/vc_row]<!-- \/wp:post-content --><\/div>","protected":false},"excerpt":{"rendered":"<p>February 21st &#038; 22nd 2023, 6:00 PM<\/p>\n","protected":false},"author":1,"featured_media":28103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[175,144],"tags":[],"class_list":["post-28101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internet-auction","category-auction"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DISCOVERY SALE<\/title>\n<meta name=\"description\" content=\"21 et 22 F\u00e9vrier 2023, 6:00 PMFebruary 21st &amp; 22nd 2023, 6:00 PM\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enchereschampagne.com\/en\/vente-decouverte\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DISCOVERY SALE\" \/>\n<meta property=\"og:description\" content=\"21 et 22 F\u00e9vrier 2023, 6:00 PMFebruary 21st &amp; 22nd 2023, 6:00 PM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enchereschampagne.com\/en\/vente-decouverte\/\" \/>\n<meta property=\"og:site_name\" content=\"Ench\u00e8res Champagne Auctions\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/champagneauctions\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-03T21:07:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-03T21:15:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev-1024x525.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/person\\\/5ee9d9f4c42b7890e9208a4e08eae9e7\"},\"headline\":\"DISCOVERY SALE\",\"datePublished\":\"2023-02-03T21:07:13+00:00\",\"dateModified\":\"2023-02-03T21:15:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev.png\",\"articleSection\":[\"Internet Auction\",\"Auction\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/#respond\"]}]},{\"@type\":\"event\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/\",\"name\":\"DISCOVERY SALE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/#primaryimage\"},\"image\":[\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev-1170x600.png\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev-300x154.png\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev-1024x525.png\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev.png\"],\"thumbnailUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev.png\",\"datePublished\":\"2023-02-03T21:07:13+00:00\",\"dateModified\":\"2023-02-03T21:15:21+00:00\",\"description\":\"February 21st & 22nd 2023, 6:00 PM\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/\"]}],\"@context\":\"https:\\\/\\\/schema.org\",\"startDate\":\"2023-02-21\",\"endDate\":\"2023-02-22\",\"eventStatus\":\"EventMovedOnline\",\"eventAttendanceMode\":\"OnlineEventAttendanceMode\",\"location\":{\"@type\":\"VirtualLocation\",\"url\":\"https:\\\/\\\/live.enchereschampagne.com\\\/\"},\"offers\":{\"@type\":\"Offer\"}},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev.png\",\"contentUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Cover-Decouverte-Fev.png\",\"width\":1920,\"height\":984},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/vente-decouverte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enchereschampagne.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VENTE D\u00c9COUVERTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#website\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/\",\"name\":\"Ench\u00e8res Champagne Auctions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enchereschampagne.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\",\"name\":\"Ench\u00e8res Champagne Auctions\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo_enchereChampagne.png\",\"contentUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo_enchereChampagne.png\",\"width\":192,\"height\":65,\"caption\":\"Ench\u00e8res Champagne Auctions\"},\"image\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/champagneauctions\",\"https:\\\/\\\/www.instagram.com\\\/champagneauctions\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/person\\\/5ee9d9f4c42b7890e9208a4e08eae9e7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DISCOVERY SALE","description":"21 et 22 F\u00e9vrier 2023, 6:00 PMFebruary 21st & 22nd 2023, 6:00 PM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enchereschampagne.com\/en\/vente-decouverte\/","og_locale":"en_US","og_type":"article","og_title":"[:fr]VENTE D\u00c9COUVERTE[:en]DISCOVERY SALE[:] - Ench\u00e8res Champagne Auctions","og_description":"21 et 22 F\u00e9vrier 2023, 6:00 PMFebruary 21st & 22nd 2023, 6:00 PM","og_url":"https:\/\/enchereschampagne.com\/en\/vente-decouverte\/","og_site_name":"Ench\u00e8res Champagne Auctions","article_publisher":"http:\/\/www.facebook.com\/champagneauctions","article_published_time":"2023-02-03T21:07:13+00:00","article_modified_time":"2023-02-03T21:15:21+00:00","og_image":[{"width":1024,"height":525,"url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev-1024x525.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/#article","isPartOf":{"@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/"},"author":{"name":"admin","@id":"https:\/\/enchereschampagne.com\/#\/schema\/person\/5ee9d9f4c42b7890e9208a4e08eae9e7"},"headline":"DISCOVERY SALE","datePublished":"2023-02-03T21:07:13+00:00","dateModified":"2023-02-03T21:15:21+00:00","mainEntityOfPage":{"@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/enchereschampagne.com\/#organization"},"image":{"@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/#primaryimage"},"thumbnailUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev.png","articleSection":["Internet Auction","Auction"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/enchereschampagne.com\/vente-decouverte\/#respond"]}]},{"@type":"event","@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/","url":"https:\/\/enchereschampagne.com\/vente-decouverte\/","name":"DISCOVERY SALE","isPartOf":{"@id":"https:\/\/enchereschampagne.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/#primaryimage"},"image":["https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev-1170x600.png","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev-300x154.png","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev-1024x525.png","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev.png"],"thumbnailUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev.png","datePublished":"2023-02-03T21:07:13+00:00","dateModified":"2023-02-03T21:15:21+00:00","description":"February 21st & 22nd 2023, 6:00 PM","breadcrumb":{"@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enchereschampagne.com\/vente-decouverte\/"]}],"@context":"https:\/\/schema.org","startDate":"2023-02-21","endDate":"2023-02-22","eventStatus":"EventMovedOnline","eventAttendanceMode":"OnlineEventAttendanceMode","location":{"@type":"VirtualLocation","url":"https:\/\/live.enchereschampagne.com\/"},"offers":{"@type":"Offer"}},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/#primaryimage","url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev.png","contentUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2023\/02\/Cover-Decouverte-Fev.png","width":1920,"height":984},{"@type":"BreadcrumbList","@id":"https:\/\/enchereschampagne.com\/vente-decouverte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enchereschampagne.com\/"},{"@type":"ListItem","position":2,"name":"VENTE D\u00c9COUVERTE"}]},{"@type":"WebSite","@id":"https:\/\/enchereschampagne.com\/#website","url":"https:\/\/enchereschampagne.com\/","name":"Ench\u00e8res Champagne Auctions","description":"","publisher":{"@id":"https:\/\/enchereschampagne.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enchereschampagne.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/enchereschampagne.com\/#organization","name":"Ench\u00e8res Champagne Auctions","url":"https:\/\/enchereschampagne.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enchereschampagne.com\/#\/schema\/logo\/image\/","url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2019\/01\/logo_enchereChampagne.png","contentUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2019\/01\/logo_enchereChampagne.png","width":192,"height":65,"caption":"Ench\u00e8res Champagne Auctions"},"image":{"@id":"https:\/\/enchereschampagne.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/champagneauctions","https:\/\/www.instagram.com\/champagneauctions"]},{"@type":"Person","@id":"https:\/\/enchereschampagne.com\/#\/schema\/person\/5ee9d9f4c42b7890e9208a4e08eae9e7","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/28101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/comments?post=28101"}],"version-history":[{"count":2,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/28101\/revisions"}],"predecessor-version":[{"id":28105,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/28101\/revisions\/28105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/media\/28103"}],"wp:attachment":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/media?parent=28101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/categories?post=28101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/tags?post=28101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}