{"id":29205,"date":"2025-12-17T20:37:32","date_gmt":"2025-12-17T20:37:32","guid":{"rendered":"https:\/\/enchereschampagne.com\/?p=29205"},"modified":"2025-12-17T20:59:40","modified_gmt":"2025-12-17T20:59:40","slug":"auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026","status":"publish","type":"post","link":"https:\/\/enchereschampagne.com\/en\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/","title":{"rendered":"Discovery sale, Pictorial Art &#8211; Session 1 &#8211; January 2026"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]\r\n<h3>January 20th 2026, 6:00 pm<\/h3>\r\n[\/vc_column_text][vc_column_text el_class=&#8221;short_hidden&#8221;]\r\n<p>We are delighted to introduce a curated selection of paintings, watercolors, pastels, charcoal drawings and lithographs for art enthusiasts and collectors alike. This session showcases a variety of works that cater to different tastes and budgets, offering a unique opportunity to discover and acquire inspiring paintings.<\/p>\r\n[\/vc_column_text][vc_column_text]\r\n<p><strong>Online auction<br \/><\/strong><!-- \/wp:post-content --><\/p>\r\n<p><!-- wp:paragraph --><a href=\"https:\/\/live.enchereschampagne.com\/auctions\/4-H8DOOO\/vente-prestige-articles-de-luxe-15-octobre-2025-19h-prestige-luxury-items-auction-october-15th-at-7pm\"><a href=\"https:\/\/live.enchereschampagne.com\/auctions\/4-IMYH8P\/dcouverte-art-pictural-session-1-janvier-2026\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#daa66e;border-color:#af8558;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#e6c19a;border-radius:5px;text-shadow:none\">  VIEW LOTS <\/span><\/a><\/a><\/p>\r\n[\/vc_column_text][vc_column_text el_class=&#8221;short_hidden&#8221;]\r\n<p>For more details on the items for sale, please contact us by phone at (438) 387-3100 or by email at info@enchereschampagne.com.<\/p>\r\n[\/vc_column_text][\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"<p>January 20, 2026 at 6 PM EDT<\/p>\n","protected":false},"author":1,"featured_media":29206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[144],"tags":[],"class_list":["post-29205","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-auction","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discovery sale, Pictorial Art - Session 1 - January 2026<\/title>\n<meta name=\"description\" content=\"20 Janvier 2026, 18:00January 20, 2026 at 6 PM EDT\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enchereschampagne.com\/en\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discovery sale, Pictorial Art - Session 1 - January 2026\" \/>\n<meta property=\"og:description\" content=\"20 Janvier 2026, 18:00January 20, 2026 at 6 PM EDT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enchereschampagne.com\/en\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Ench\u00e8res Champagne Auctions\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/champagneauctions\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-17T20:37:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T20:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/person\\\/5ee9d9f4c42b7890e9208a4e08eae9e7\"},\"headline\":\"Discovery sale, Pictorial Art &#8211; Session 1 &#8211; January 2026\",\"datePublished\":\"2025-12-17T20:37:32+00:00\",\"dateModified\":\"2025-12-17T20:59:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4.jpg\",\"articleSection\":[\"Auction\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/#respond\"]}]},{\"@type\":\"event\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/\",\"name\":\"Discovery sale, Pictorial Art - Session 1 - January 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/#primaryimage\"},\"image\":[\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4.jpg\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4-300x300.jpg\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4-1024x1024.jpg\",\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4.jpg\"],\"thumbnailUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4.jpg\",\"datePublished\":\"2025-12-17T20:37:32+00:00\",\"dateModified\":\"2025-12-17T20:59:40+00:00\",\"description\":\"January 20, 2026 at 6 PM EDT\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/\"]}],\"@context\":\"https:\\\/\\\/schema.org\",\"startDate\":\"2025-10-15\",\"endDate\":\"2025-10-15\",\"eventStatus\":\"EventScheduled\",\"eventAttendanceMode\":\"MixedEventAttendanceMode\",\"location\":[{\"@type\":\"VirtualLocation\",\"url\":\"https:\\\/\\\/live.enchereschampagne.com\\\/\"},{\"@type\":\"place\",\"name\":\"\",\"address\":\"\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"\",\"longitude\":\"\"}}],\"offers\":{\"@type\":\"Offer\"}},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4.jpg\",\"contentUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1950-Ste-Catherine-EST-4.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enchereschampagne.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vente D\u00e9couverte, Art pictural &#8211; Session 1 &#8211; Janvier 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#website\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/\",\"name\":\"Ench\u00e8res Champagne Auctions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enchereschampagne.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#organization\",\"name\":\"Ench\u00e8res Champagne Auctions\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo_enchereChampagne.png\",\"contentUrl\":\"https:\\\/\\\/enchereschampagne.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo_enchereChampagne.png\",\"width\":192,\"height\":65,\"caption\":\"Ench\u00e8res Champagne Auctions\"},\"image\":{\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/champagneauctions\",\"https:\\\/\\\/www.instagram.com\\\/champagneauctions\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/enchereschampagne.com\\\/#\\\/schema\\\/person\\\/5ee9d9f4c42b7890e9208a4e08eae9e7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discovery sale, Pictorial Art - Session 1 - January 2026","description":"20 Janvier 2026, 18:00January 20, 2026 at 6 PM EDT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enchereschampagne.com\/en\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/","og_locale":"en_US","og_type":"article","og_title":"[:fr]Vente D\u00e9couverte, Art pictural - Session 1 - Janvier 2026[:en]Discovery sale, Pictorial Art - Session 1 - January 2026[:] - Ench\u00e8res Champagne Auctions","og_description":"20 Janvier 2026, 18:00January 20, 2026 at 6 PM EDT","og_url":"https:\/\/enchereschampagne.com\/en\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/","og_site_name":"Ench\u00e8res Champagne Auctions","article_publisher":"http:\/\/www.facebook.com\/champagneauctions","article_published_time":"2025-12-17T20:37:32+00:00","article_modified_time":"2025-12-17T20:59:40+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/#article","isPartOf":{"@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/"},"author":{"name":"admin","@id":"https:\/\/enchereschampagne.com\/#\/schema\/person\/5ee9d9f4c42b7890e9208a4e08eae9e7"},"headline":"Discovery sale, Pictorial Art &#8211; Session 1 &#8211; January 2026","datePublished":"2025-12-17T20:37:32+00:00","dateModified":"2025-12-17T20:59:40+00:00","mainEntityOfPage":{"@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/enchereschampagne.com\/#organization"},"image":{"@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg","articleSection":["Auction"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/#respond"]}]},{"@type":"event","@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/","url":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/","name":"Discovery sale, Pictorial Art - Session 1 - January 2026","isPartOf":{"@id":"https:\/\/enchereschampagne.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/#primaryimage"},"image":["https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4-300x300.jpg","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4-1024x1024.jpg","https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg"],"thumbnailUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg","datePublished":"2025-12-17T20:37:32+00:00","dateModified":"2025-12-17T20:59:40+00:00","description":"January 20, 2026 at 6 PM EDT","breadcrumb":{"@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/"]}],"@context":"https:\/\/schema.org","startDate":"2025-10-15","endDate":"2025-10-15","eventStatus":"EventScheduled","eventAttendanceMode":"MixedEventAttendanceMode","location":[{"@type":"VirtualLocation","url":"https:\/\/live.enchereschampagne.com\/"},{"@type":"place","name":"","address":"","geo":{"@type":"GeoCoordinates","latitude":"","longitude":""}}],"offers":{"@type":"Offer"}},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/#primaryimage","url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg","contentUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2025\/12\/1950-Ste-Catherine-EST-4.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/enchereschampagne.com\/auctions-4-imyh8p-dcouverte-art-pictural-session-1-janvier-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enchereschampagne.com\/"},{"@type":"ListItem","position":2,"name":"Vente D\u00e9couverte, Art pictural &#8211; Session 1 &#8211; Janvier 2026"}]},{"@type":"WebSite","@id":"https:\/\/enchereschampagne.com\/#website","url":"https:\/\/enchereschampagne.com\/","name":"Ench\u00e8res Champagne Auctions","description":"","publisher":{"@id":"https:\/\/enchereschampagne.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enchereschampagne.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/enchereschampagne.com\/#organization","name":"Ench\u00e8res Champagne Auctions","url":"https:\/\/enchereschampagne.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enchereschampagne.com\/#\/schema\/logo\/image\/","url":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2019\/01\/logo_enchereChampagne.png","contentUrl":"https:\/\/enchereschampagne.com\/wp-content\/uploads\/2019\/01\/logo_enchereChampagne.png","width":192,"height":65,"caption":"Ench\u00e8res Champagne Auctions"},"image":{"@id":"https:\/\/enchereschampagne.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/champagneauctions","https:\/\/www.instagram.com\/champagneauctions"]},{"@type":"Person","@id":"https:\/\/enchereschampagne.com\/#\/schema\/person\/5ee9d9f4c42b7890e9208a4e08eae9e7","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a477ed377e16a6723657bb9a8758ceb437b417a828bb5d49f86fc9fd48d4b21b?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/29205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/comments?post=29205"}],"version-history":[{"count":9,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/29205\/revisions"}],"predecessor-version":[{"id":29221,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/posts\/29205\/revisions\/29221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/media\/29206"}],"wp:attachment":[{"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/media?parent=29205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/categories?post=29205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enchereschampagne.com\/en\/wp-json\/wp\/v2\/tags?post=29205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}